{"id":5029,"date":"2024-07-10T10:30:24","date_gmt":"2024-07-10T03:30:24","guid":{"rendered":"http:\/\/www.intania.com\/?p=5029"},"modified":"2024-07-31T11:22:12","modified_gmt":"2024-07-31T04:22:12","slug":"y2quantum-2023","status":"publish","type":"post","link":"https:\/\/www.intania.com\/en\/y2quantum-2023\/","title":{"rendered":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5029\" class=\"elementor elementor-5029\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5092e96 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5092e96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8bc60b\" data-id=\"e8bc60b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3333668 elementor-widget elementor-widget-heading\" data-id=\"3333668\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d2c5f elementor-widget elementor-widget-text-editor\" data-id=\"c4d2c5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e28\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c (\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e01\u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e08\u0e38\u0e2c\u0e32\u0e2f \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1f\u0e32\u0e27\u0e40\u0e14\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e35\u0e41\u0e25\u0e30 Chinese Academy of Sciences\n<br>\n\u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u0e40\u0e27\u0e25\u0e32 09.00-12.00 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e0a\u0e31\u0e49\u0e19 2 \u0e15\u0e36\u0e01 4 (\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21)\n<br>\n\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e41\u0e01\u0e19 QR Code \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\n<br>\n\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e28\u0e34\u0e23\u0e34\u0e01\u0e31\u0e0d\u0e0d\u0e32 \u0e1e\u0e07\u0e29\u0e4c\u0e17\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\n<br>\n\ud83d\udcde\u0e42\u0e17\u0e23: 02-218-7812\n<br>\n\ud83d\udcbbE-mail: Sirikanya.po@chula.ac.th\n<br>\n**\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29**\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d68113 elementor-widget elementor-widget-image\" data-id=\"6d68113\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/dms.sundaedms.com:81\/intania\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"18132625-5E0B-408A-ADCE-1B668EF682D5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTAzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5pbnRhbmlhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDdcLzE4MTMyNjI1LTVFMEItNDA4QS1BRENFLTFCNjY4RUY2ODJENS5qcGVnIn0%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5-724x1024.jpeg\" class=\"attachment-large size-large wp-image-5031\" alt=\"\" srcset=\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5-724x1024.jpeg 724w, https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5-212x300.jpeg 212w, https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5-768x1086.jpeg 768w, https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg 1076w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e28\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c (\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e01\u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e08\u0e38\u0e2c\u0e32\u0e2f \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1f\u0e32\u0e27\u0e40\u0e14\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":5031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[],"class_list":["post-5029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intania.com\/en\/y2quantum-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\" \/>\n<meta property=\"og:description\" content=\"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e28\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c (\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e01\u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e08\u0e38\u0e2c\u0e32\u0e2f \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1f\u0e32\u0e27\u0e40\u0e14\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intania.com\/en\/y2quantum-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ChulaEngineeringAlumni\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T03:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T04:22:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1076\" \/>\n\t<meta property=\"og:image:height\" content=\"1522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sundaeadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sundaeadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/\"},\"author\":{\"name\":\"sundaeadmin\",\"@id\":\"https:\/\/www.intania.com\/#\/schema\/person\/8af8349152424715422aaf9523a266c7\"},\"headline\":\"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"datePublished\":\"2024-07-10T03:30:24+00:00\",\"dateModified\":\"2024-07-31T04:22:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/\"},\"wordCount\":15,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.intania.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.intania.com\/y2quantum-2023\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/\",\"url\":\"https:\/\/www.intania.com\/y2quantum-2023\/\",\"name\":\"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\",\"isPartOf\":{\"@id\":\"https:\/\/www.intania.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\",\"datePublished\":\"2024-07-10T03:30:24+00:00\",\"dateModified\":\"2024-07-31T04:22:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intania.com\/y2quantum-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage\",\"url\":\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\",\"contentUrl\":\"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg\",\"width\":1076,\"height\":1522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intania.com\/y2quantum-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\/\/www.intania.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\",\"item\":\"https:\/\/www.intania.com\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intania.com\/#website\",\"url\":\"https:\/\/www.intania.com\/\",\"name\":\"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intania.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intania.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intania.com\/#organization\",\"name\":\"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\",\"url\":\"https:\/\/www.intania.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.intania.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/dms.sundaedms.com:81\/intania\/wp-content\/uploads\/2024\/07\/logo-intania-1.png\",\"contentUrl\":\"http:\/\/dms.sundaedms.com:81\/intania\/wp-content\/uploads\/2024\/07\/logo-intania-1.png\",\"width\":80,\"height\":80,\"caption\":\"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI\"},\"image\":{\"@id\":\"https:\/\/www.intania.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ChulaEngineeringAlumni\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intania.com\/#\/schema\/person\/8af8349152424715422aaf9523a266c7\",\"name\":\"sundaeadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.intania.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bbbe092a30fe59570c413d86c307a09245136360ee65fdfafbdfec0b211ddadf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bbbe092a30fe59570c413d86c307a09245136360ee65fdfafbdfec0b211ddadf?s=96&d=mm&r=g\",\"caption\":\"sundaeadmin\"},\"sameAs\":[\"http:\/\/dms.sundaedms.com:81\/intania\"],\"url\":\"https:\/\/www.intania.com\/en\/author\/sundaeadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intania.com\/en\/y2quantum-2023\/","og_locale":"en_US","og_type":"article","og_title":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","og_description":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e28\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e13 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c (\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e01\u0e25\u0e32\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2d\u0e23\u0e38\u0e13 \u0e2a\u0e23\u0e40\u0e17\u0e28\u0e19\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e08\u0e38\u0e2c\u0e32\u0e2f \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1f\u0e32\u0e27\u0e40\u0e14\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 [&hellip;]","og_url":"https:\/\/www.intania.com\/en\/y2quantum-2023\/","og_site_name":"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","article_publisher":"https:\/\/www.facebook.com\/ChulaEngineeringAlumni\/","article_published_time":"2024-07-10T03:30:24+00:00","article_modified_time":"2024-07-31T04:22:12+00:00","og_image":[{"width":1076,"height":1522,"url":"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg","type":"image\/jpeg"}],"author":"sundaeadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sundaeadmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intania.com\/y2quantum-2023\/#article","isPartOf":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/"},"author":{"name":"sundaeadmin","@id":"https:\/\/www.intania.com\/#\/schema\/person\/8af8349152424715422aaf9523a266c7"},"headline":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","datePublished":"2024-07-10T03:30:24+00:00","dateModified":"2024-07-31T04:22:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/"},"wordCount":15,"commentCount":0,"publisher":{"@id":"https:\/\/www.intania.com\/#organization"},"image":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.intania.com\/y2quantum-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.intania.com\/y2quantum-2023\/","url":"https:\/\/www.intania.com\/y2quantum-2023\/","name":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c - \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","isPartOf":{"@id":"https:\/\/www.intania.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg","datePublished":"2024-07-10T03:30:24+00:00","dateModified":"2024-07-31T04:22:12+00:00","breadcrumb":{"@id":"https:\/\/www.intania.com\/y2quantum-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intania.com\/y2quantum-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intania.com\/y2quantum-2023\/#primaryimage","url":"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg","contentUrl":"https:\/\/www.intania.com\/wp-content\/uploads\/2024\/07\/18132625-5E0B-408A-ADCE-1B668EF682D5.jpeg","width":1076,"height":1522},{"@type":"BreadcrumbList","@id":"https:\/\/www.intania.com\/y2quantum-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.intania.com\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23","item":"https:\/\/www.intania.com\/category\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e01\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c"}]},{"@type":"WebSite","@id":"https:\/\/www.intania.com\/#website","url":"https:\/\/www.intania.com\/","name":"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","description":"","publisher":{"@id":"https:\/\/www.intania.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intania.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.intania.com\/#organization","name":"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI","url":"https:\/\/www.intania.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intania.com\/#\/schema\/logo\/image\/","url":"http:\/\/dms.sundaedms.com:81\/intania\/wp-content\/uploads\/2024\/07\/logo-intania-1.png","contentUrl":"http:\/\/dms.sundaedms.com:81\/intania\/wp-content\/uploads\/2024\/07\/logo-intania-1.png","width":80,"height":80,"caption":"\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u2013 CHULALONGKORN UNIVERSITY ENGINEERING ALUMNI"},"image":{"@id":"https:\/\/www.intania.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ChulaEngineeringAlumni\/"]},{"@type":"Person","@id":"https:\/\/www.intania.com\/#\/schema\/person\/8af8349152424715422aaf9523a266c7","name":"sundaeadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intania.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bbbe092a30fe59570c413d86c307a09245136360ee65fdfafbdfec0b211ddadf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbbe092a30fe59570c413d86c307a09245136360ee65fdfafbdfec0b211ddadf?s=96&d=mm&r=g","caption":"sundaeadmin"},"sameAs":["http:\/\/dms.sundaedms.com:81\/intania"],"url":"https:\/\/www.intania.com\/en\/author\/sundaeadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/posts\/5029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/comments?post=5029"}],"version-history":[{"count":0,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/posts\/5029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/media\/5031"}],"wp:attachment":[{"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/media?parent=5029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/categories?post=5029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intania.com\/en\/wp-json\/wp\/v2\/tags?post=5029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}